{"id":6753,"date":"2020-12-07T16:01:05","date_gmt":"2020-12-07T16:01:05","guid":{"rendered":"https:\/\/ficusplant.org\/?page_id=6753"},"modified":"2022-05-19T14:38:09","modified_gmt":"2022-05-19T14:38:09","slug":"ficus-auriculata","status":"publish","type":"page","link":"https:\/\/ficusplant.org\/de\/ficus-auriculata\/","title":{"rendered":"Ficus Auriculata: Tipps f\u00fcr Pflege, Vermehrung und Verpflanzung"},"content":{"rendered":"<p>Eine sehr exotische Pflanze &#8211; Ficus Auriculata &#8211; ist aus den fernen tropischen W\u00e4ldern Indiens und S\u00fcdostasiens zu uns gekommen. Ihren Namen verdankt sie den gro\u00dfen Bl\u00e4ttern, die ein wenig an Elefantenohren erinnern &#8211; dies ist ein weiterer Name dieser Pflanze. Ein fantastischer, schnell wachsender, kleiner Baum oder Strauch von bis zu 8 m H\u00f6he mit riesigen, runden Bl\u00e4ttern, die einen Durchmesser von bis zu 40 cm erreichen k\u00f6nnen und im Austrieb eine wunderbare kupferne Farbe haben.<\/p>\n<p><img loading=\"lazy\" class=\"size-medium wp-image-314 aligncenter\" src=\"http:\/\/ficusplant.org\/wp-content\/uploads\/2021\/06\/Screenshot_1-1-300x202.png\" alt=\"Ficus auriculata - Giant fig\" width=\"400\" height=\"280\" \/><\/p>\n<p>Der Ficus Auriculata selbst ist ein ewig gr\u00fcner Baum oder ein mittelgro\u00dfer Strauch (manchmal halbbl\u00e4ttrige Vertreter) mit tiefh\u00e4ngenden \u00c4sten. In der nat\u00fcrlichen Umgebung tr\u00e4gt die Pflanze reichlich Sykonien, die gro\u00dfen Feigen \u00e4hneln. Nach der Befruchtung durch eine winzige Wespe, die in Symbiose mit der Pflanze lebt, erscheinen die gro\u00dfen Fr\u00fcchte am Stamm und an den Haupt\u00e4sten; sie sind essbar und s\u00fc\u00df.<\/p>\n<p>Auf dem Foto k\u00f6nnen Sie sich diese au\u00dfergew\u00f6hnliche Pflanze genauer ansehen:<\/p>\n<p><img loading=\"lazy\" class=\"size-medium wp-image-317 aligncenter\" src=\"http:\/\/ficusplant.org\/wp-content\/uploads\/2021\/06\/Screenshot_4-1-300x175.png\" alt=\"Ficus Auriculata photo\" width=\"400\" height=\"225\" \/><\/p>\n<h2>Pflege von Ficus Auriculata zu Hause<\/h2>\n<p><iframe loading=\"lazy\" title=\"John, Ficus auriculata, fig tree\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/iTa-QK6eCTQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p>Nat\u00fcrlich ist es aus objektiven Gr\u00fcnden schwierig, einen so gro\u00dfen Ficus zu Hause anzubauen. Oft ist es f\u00fcr die Landschaftsgestaltung gro\u00dfe B\u00fcrofl\u00e4chen oder Hallen geeignet. Und doch waren virtuose Floristen in der Lage, von Ficus Auriculata bansai, die leicht in ein kleines Wohnzimmer passen kann wachsen, sowie geben einige Tipps, wie man die Pflanze richtige Pflege zu gew\u00e4hrleisten.<\/p>\n<ul>\n<li><strong>Beleuchtung:<\/strong> Es wird empfohlen, helles Licht f\u00fcr Ficus zu organisieren, auch mit einer kleinen Menge an direktem Sonnenlicht, zum Beispiel am Morgen oder am Abend.<\/li>\n<li><strong>Bew\u00e4sserung:<\/strong> Die Erde muss stets m\u00e4\u00dfig feucht gehalten werden, aber der Ficus darf nicht \u00fcberschwemmt werden.<\/li>\n<li><strong>Temperatur:<\/strong> Der optimale Temperaturrahmen f\u00fcr Ficus Auriculata liegt zwischen +64,4\u00b0F und +78,8\u00b0F im Sommer und zwischen +59\u00b0F und +68\u00b0F im Winter.<\/li>\n<li><strong>F\u00fctterung:<\/strong> Es wird empfohlen, die Pflanze vom Sp\u00e4twinter bis zum Fr\u00fchherbst alle zwei Wochen mit organischem oder mineralischem D\u00fcnger zu versorgen. Im Winter kann man sie einmal im Monat d\u00fcngen.<\/li>\n<li><strong>Vermehrung:<\/strong> Kann durch Stecklinge oder Samen im zeitigen Fr\u00fchjahr vermehrt werden.<\/li>\n<li><strong>Boden:<\/strong> F\u00fcr die Anpflanzung des Ficus eignet sich am besten eine Mischung aus Torf, Blatterde und Sand. Die Mischung sollte \u00fcppig und leicht sein, damit gen\u00fcgend Luft an die Wurzeln gelangen kann.<\/li>\n<\/ul>\n<p>Mit diesen einfachen Regeln k\u00f6nnen Sie also versuchen, Ficus Auriculata selbst zu z\u00fcchten.<\/p>\n<figure id=\"attachment_220\" aria-describedby=\"caption-attachment-220\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" class=\"wp-image-220 size-medium\" src=\"http:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/2288012984_97cc22eab9_b-300x225.jpg\" alt=\"Ficus Auriculata\" width=\"300\" height=\"225\" srcset=\"https:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/2288012984_97cc22eab9_b-300x225.jpg 300w, https:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/2288012984_97cc22eab9_b.jpg 550w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-220\" class=\"wp-caption-text\">Ficus Auriculata f\u00fcr die Pflege<\/figcaption><\/figure>\n<p>Was die Schwierigkeiten bei der Pflege, hier auf der Arena kommen die gemeinsamen Fehler der Besitzer von ficuses. Zum Beispiel, unter ihnen sind \u00dcberbefeuchtung des Bodens, die zu Wurzeln verrotten f\u00fchren kann, oder Mangel an Feuchtigkeit wird durch fallende Bl\u00e4tter begleitet werden. Auch negativ auf die Anlage und trockene warme Luft w\u00e4hrend der Heizperiode, die manchmal auf das Auftreten von Sch\u00e4dlingen beitr\u00e4gt.<\/p>\n<p>Wenn Sie diese Empfehlungen befolgen und versuchen, Fehler in der Pflege zu vermeiden, wird die auricular ficus stark und gesund wachsen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eine sehr exotische Pflanze &#8211; Ficus Auriculata &#8211; ist aus den fernen tropischen W\u00e4ldern Indiens und S\u00fcdostasiens zu uns gekommen. Ihren Namen verdankt sie den gro\u00dfen Bl\u00e4ttern, die ein wenig an Elefantenohren erinnern &#8211; dies ist ein weiterer Name dieser<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/ficusplant.org\/de\/wp-json\/wp\/v2\/pages\/6753"}],"collection":[{"href":"https:\/\/ficusplant.org\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ficusplant.org\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ficusplant.org\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ficusplant.org\/de\/wp-json\/wp\/v2\/comments?post=6753"}],"version-history":[{"count":2,"href":"https:\/\/ficusplant.org\/de\/wp-json\/wp\/v2\/pages\/6753\/revisions"}],"predecessor-version":[{"id":6755,"href":"https:\/\/ficusplant.org\/de\/wp-json\/wp\/v2\/pages\/6753\/revisions\/6755"}],"wp:attachment":[{"href":"https:\/\/ficusplant.org\/de\/wp-json\/wp\/v2\/media?parent=6753"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}