{"id":5257,"date":"2020-10-07T09:23:13","date_gmt":"2020-10-07T09:23:13","guid":{"rendered":"https:\/\/ficusplant.org\/?page_id=5257"},"modified":"2022-05-11T08:04:19","modified_gmt":"2022-05-11T08:04:19","slug":"tipos-de-ficcion","status":"publish","type":"page","link":"https:\/\/ficusplant.org\/es\/tipos-de-ficcion\/","title":{"rendered":"Principales especies de ficus y sus cuidados"},"content":{"rendered":"<p>La mayor\u00eda de la gente piensa que s\u00f3lo existe un tipo de Ficus, pero en realidad, este \u00e1rbol en particular viene en una variedad de formas y tama\u00f1os basados en la variedad espec\u00edfica. Por ejemplo, algunas de las opciones m\u00e1s populares son el Amstel King, Indigo, Midnight, Monique y Wiandi. Independientemente del tipo de Ficus que elija, le encantar\u00e1 la belleza de su follaje, que puede mejorar el aspecto de cualquier habitaci\u00f3n.<\/p>\n<p>Si quiere conocer esta planta m\u00e1s de cerca, para saber m\u00e1s sobre los tipos de ficus que existen, le invitamos a que nos acompa\u00f1e en un apasionante viaje por una gran variedad de formas y colores, a partir de los cuales la cabeza s\u00f3lo da vueltas.<\/p>\n<p>Principales especiesSe presentan a su atenci\u00f3n las variedades de ficus que se pueden cultivar en casa.<\/p>\n<h2>Ficus Benjamina<\/h2>\n<p>Para una planta dom\u00e9stica, el tipo de Ficus m\u00e1s popular es el Benjamina. Aunque es hermoso y una de las opciones favoritas, lamentablemente, este tipo particular de Ficus puede ser dif\u00edcil de cultivar. A este \u00e1rbol tambi\u00e9n se le llama \u00abhiguera llorona\u00bb porque las ramas lloran o se caen de forma natural. Uno de los problemas asociados a este \u00e1rbol es que las hojas se caen con facilidad. Sin embargo, una vez que se entienden las razones por las que las hojas se caen, se pueden hacer los ajustes adecuados para que el problema sea inexistente.<\/p>\n<p>La mayor\u00eda de la gente piensa que este tipo de \u00e1rbol Ficus es d\u00e9bil o delicado debido a las hojas que lloran y se caen, pero en realidad es bastante fuerte y resistente. Por lo general, cuando se lleva un Ficus de este tipo a casa y, de repente, el \u00e1rbol perfecto que vio en el vivero o la tienda ahora parece pat\u00e9tico, es porque el \u00e1rbol se est\u00e1 aclimatando a su nuevo entorno. Esto significa que se est\u00e1 acostumbrando al nuevo entorno de temperatura y luz.<\/p>\n<p>Adem\u00e1s, al ficus benjamina tambi\u00e9n se le caen las hojas porque no se le ha regado lo suficiente. Por lo general, regar la planta la devolver\u00e1 inmediatamente a la vida. Esto es siempre importante, pero especialmente durante el verano, que se considera la \u00abestaci\u00f3n seca\u00bb. Aunque la mayor\u00eda de la gente piensa que algo ha ido terriblemente mal, en la mayor\u00eda de los casos, la ca\u00edda o desprendimiento de las hojas no es nada grave.<\/p>\n<figure id=\"attachment_45\" aria-describedby=\"caption-attachment-45\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" class=\"wp-image-45 size-medium\" src=\"http:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/FICUS_BENJAMINA-300x300.jpg\" alt=\"FICUS_BENJAMINA\" width=\"300\" height=\"300\" srcset=\"https:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/FICUS_BENJAMINA-300x300.jpg 300w, https:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/FICUS_BENJAMINA-150x150.jpg 150w, https:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/FICUS_BENJAMINA-230x230.jpg 230w, https:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/FICUS_BENJAMINA-365x365.jpg 365w, https:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/FICUS_BENJAMINA.jpg 500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-45\" class=\"wp-caption-text\">Foto del Ficus Benjamina<\/figcaption><\/figure>\n<p>Para cultivar un Ficus, hay que asegurarse de plantarlo en una maceta que soporte el tama\u00f1o actual de las ra\u00edces, pero que tambi\u00e9n ofrezca espacio adicional cuando la planta crezca.\u00a0 Adem\u00e1s, el \u00e1rbol necesita un suelo rico y saludable que debe estar ligeramente h\u00famedo.\u00a0 Aseg\u00farese de que el Ficus no se riegue en exceso, ya que esto podr\u00eda provocar la putrefacci\u00f3n de las ra\u00edces, lo que podr\u00eda matar a la planta.<\/p>\n<p>Tambi\u00e9n es importante que el \u00e1rbol de Ficus que elija tenga la mayor cantidad de luz solar posible.\u00a0 Por lo tanto, cuando decida comprar este tipo de planta, aseg\u00farese de tener un lugar que le proporcione mucha luz solar.\u00a0 Mientras que esto estar\u00eda cerca de una ventana, apenas se cerciora de que el \u00e1rbol de Ficus no se est\u00e1 sujetando al fr\u00edo o al viento.<\/p>\n<p>Lamentablemente, mucha gente pasa de comprar un Ficus por todas las historias de terror, pero con un poco de cuidado y unos simples consejos, su \u00e1rbol florecer\u00e1.\u00a0 Una vez que el \u00e1rbol se haya asentado en su nuevo hogar y se haya cuidado adecuadamente, tendr\u00e1s una gruesa y hermosa adici\u00f3n al hogar.<\/p>\n<p>Cuidados:<\/p>\n<ul>\n<li>No le gusta el riego frecuente.<\/li>\n<li>No tolera la luz solar directa.<\/li>\n<li>Dependiendo del color de las hojas puede estar tanto en la sombra como en un lugar luminoso.<\/li>\n<\/ul>\n<h2>Ficus Elastica<\/h2>\n<figure id=\"attachment_46\" aria-describedby=\"caption-attachment-46\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" class=\"wp-image-46 size-medium\" src=\"http:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/Ficus-Elastica-300x248.jpg\" alt=\"Ficus Elastica\" width=\"300\" height=\"248\" srcset=\"https:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/Ficus-Elastica-300x248.jpg 300w, https:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/Ficus-Elastica.jpg 550w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-46\" class=\"wp-caption-text\">Foto de Ficus Elastica<\/figcaption><\/figure>\n<p>Este tipo de ficus se caracteriza por sus enormes hojas cori\u00e1ceas de color verde oscuro o con manchas claras. Por lo general, en condiciones decorativas, la planta no se ramifica &#8211; las hojas se encuentran en el tronco, que, con buen cuidado, puede alcanzar una longitud de hasta 2 metros. Y no es extra\u00f1o, porque el Ficus Elastica desde principios de primavera hasta finales de oto\u00f1o puede a\u00f1adir una hoja a la semana. A veces en las hojas hay un jugo l\u00e1cteo, que se utiliza en la industria para producir caucho, pero la propia planta cura sus heridas o ahuyenta las plagas. Puede ser irritante si entra en contacto con la piel. Cuidados:<\/p>\n<ul>\n<li>Prefiere la luz brillante pero difusa de la luz solar directa.<\/li>\n<li>Le gusta la temperatura moderada tanto en verano (+68\u00b0F &#8211; +77\u00b0F) como en invierno (no menos de +59\u00b0F).<\/li>\n<li>Antes de cada riego, la tierra debe secarse.<\/li>\n<\/ul>\n<h2>Ficus Benghalensis<\/h2>\n<figure id=\"attachment_44\" aria-describedby=\"caption-attachment-44\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" class=\"wp-image-44 size-medium\" src=\"http:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/Ficus-Benjamina-300x264.jpg\" alt=\"Ficus Benghalensis\" width=\"300\" height=\"264\" srcset=\"https:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/Ficus-Benjamina-300x264.jpg 300w, https:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/Ficus-Benjamina.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-44\" class=\"wp-caption-text\">Foto del Ficus Benghalensis<\/figcaption><\/figure>\n<p>El Ficus Benghalensis es un \u00e1rbol de hoja perenne que tiene una forma de vida de baniano en su h\u00e1bitat natural. As\u00ed, al \u00abasentarse\u00bb sobre una planta m\u00e1s grande y fuerte, el ficus libera ra\u00edces a\u00e9reas que, al llegar al suelo, comienzan a echar ra\u00edces y se convierten en un tronco ordinario. Las hojas de esta especie tienen una forma ovalada, el color verde de la placa con las venas de color verde claro. En condiciones de sala puede alcanzar los 3 metros de altura, mientras que en la naturaleza &#8211; hasta 40 metros. Cuidados:<\/p>\n<ul>\n<li>Planta amante de la luz (sin luz solar directa).<\/li>\n<li>Le gustan las temperaturas moderadas de +57,2\u00b0F en invierno a +86\u00b0F en verano.<\/li>\n<li>Requiere un riego moderado, excepto en el per\u00edodo de crecimiento activo, en el que conviene regar m\u00e1s a menudo.<\/li>\n<\/ul>\n<h2>Ficus Binnendijkii<\/h2>\n<figure id=\"attachment_47\" aria-describedby=\"caption-attachment-47\" style=\"width: 225px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" class=\"wp-image-47 size-medium\" src=\"http:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/Ficus-Binnendijkii-225x300.jpg\" alt=\"Ficus Binnendijkii\" width=\"225\" height=\"300\" srcset=\"https:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/Ficus-Binnendijkii-225x300.jpg 225w, https:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/Ficus-Binnendijkii.jpg 300w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><figcaption id=\"caption-attachment-47\" class=\"wp-caption-text\">Foto de Ficus Binnendijkii<\/figcaption><\/figure>\n<p>El Ficus Binnendijkii es un ficus de hoja perenne, con forma de arbusto o de \u00e1rbol. La corteza de una planta adulta es algo \u00e1spera, de color gris claro con trazos blancos. Las hojas son oblongas, brillantes y lisas, de 25 a 30 cm de largo y de 4 a 4,5 cm de ancho. El color de las hojas puede ser monocromo -verde oscuro- o moteado -con manchas de color-. Cuidados:<\/p>\n<ul>\n<li>Las temperaturas son moderadas, de +55,4\u00b0F en invierno a +77\u00b0F en verano.<\/li>\n<li>La planta prefiere la luz difusa o una penumbra ligera.<\/li>\n<li>El riego se realiza en verano cuando la capa superior de la tierra se ha secado, en invierno cuando toda la tierra de la maceta se ha secado.<\/li>\n<\/ul>\n<h2>Ficus Pumila<\/h2>\n<figure id=\"attachment_48\" aria-describedby=\"caption-attachment-48\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" class=\"wp-image-48 size-medium\" src=\"http:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/Ficus-Pumila-300x300.jpg\" alt=\"Ficus Pumila\" width=\"300\" height=\"300\" srcset=\"https:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/Ficus-Pumila-300x300.jpg 300w, https:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/Ficus-Pumila-150x150.jpg 150w, https:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/Ficus-Pumila-230x230.jpg 230w, https:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/Ficus-Pumila.jpg 350w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-48\" class=\"wp-caption-text\">Foto de Ficus Pumila<\/figcaption><\/figure>\n<p>Este tipo de ficus es fundamentalmente diferente de los anteriores. En primer lugar, no es un \u00e1rbol ni un arbusto, sino una planta herb\u00e1cea, capaz de enraizar con sus propios brotes. En resumen, los brotes son delgados, flexibles, abundantemente cubiertos de hojas. Las hojas pueden ser redondeadas u oblongas, seg\u00fan la variedad. El color tambi\u00e9n es diferente: desde el verde claro, mon\u00f3tono hasta abigarrado. Cuidados:<\/p>\n<ul>\n<li>Puede soportar la temperatura m\u00e1s baja de +46,4\u00b0F en invierno, y la m\u00e1s alta de +77\u00b0F en verano.<\/li>\n<li>Le encanta un poco de sol por la ma\u00f1ana o por la noche, por ejemplo, y la luz dispersa.<\/li>\n<li>El riego es bastante abundante; no deje que la tierra se seque por completo.<\/li>\n<\/ul>\n<h2>Ficus\u00a0Triangularis<\/h2>\n<figure id=\"attachment_26\" aria-describedby=\"caption-attachment-26\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" class=\"wp-image-26 size-medium\" src=\"http:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/1702354941_63d2a6c3fd-300x225.jpg\" alt=\"Ficus triangularis\" width=\"300\" height=\"225\" srcset=\"https:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/1702354941_63d2a6c3fd-300x225.jpg 300w, https:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/1702354941_63d2a6c3fd.jpg 500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-26\" class=\"wp-caption-text\">Foto del Ficus Triangularis<\/figcaption><\/figure>\n<p>Peque\u00f1o \u00e1rbol o arbusto con hojas de forma triangular. La corteza es marr\u00f3n, los brotes son el\u00e1sticos. Las hojas son cori\u00e1ceas, de color no mon\u00f3tono: predominan el verde, el verde claro y el blanco. Hay una vena c\u00f3ncava en el centro de la hoja. Se deja:<\/p>\n<ul>\n<li>En invierno le gusta el calor, la temperatura m\u00ednima es de +60,8\u00b0F, y en verano la m\u00e1xima es de +77\u00b0F.<\/li>\n<li>Le gusta la humedad alta, las pulverizaciones diarias.<\/li>\n<li>No tolera la luz solar directa.<\/li>\n<\/ul>\n<h2>Ficus Lyrata<\/h2>\n<figure id=\"attachment_50\" aria-describedby=\"caption-attachment-50\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" class=\"wp-image-50 size-medium\" src=\"http:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/Ficus-Lyrata-300x225.jpg\" alt=\"Ficus Lyrata\" width=\"300\" height=\"225\" srcset=\"https:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/Ficus-Lyrata-300x225.jpg 300w, https:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/Ficus-Lyrata.jpg 480w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-50\" class=\"wp-caption-text\">Foto de Ficus Lyrata<\/figcaption><\/figure>\n<p>Los nombres de muchas especies de ficus tienen su origen en su h\u00e1bitat o en la forma de las hojas. As\u00ed, las hojas de un \u00e1rbol con forma de lira se parecen realmente a un viol\u00edn o a una lira. Son bastante grandes, hasta 50 cm de largo y 25 cm de ancho. Son de color verde oscuro, cori\u00e1ceas, el\u00e1sticas, un poco arrugadas y con una vena pronunciada. La corteza del tronco es rugosa, de color gris-marr\u00f3n. Las ra\u00edces a\u00e9reas se expresan mal o est\u00e1n ausentes. Cuidados:<\/p>\n<ul>\n<li>Requiere mantener condiciones cercanas a las naturales &#8211; le gusta la humedad alta.<\/li>\n<li>No tolera la luz solar directa.<\/li>\n<li>Sensible a los cambios bruscos de temperatura.<\/li>\n<\/ul>\n<h2>Ficus\u00a0Retusa<\/h2>\n<figure id=\"attachment_52\" aria-describedby=\"caption-attachment-52\" style=\"width: 236px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" class=\"wp-image-52 size-medium\" src=\"http:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/Ficus-Retusa-236x300.jpg\" alt=\"Ficus\u00a0Retusa\" width=\"236\" height=\"300\" srcset=\"https:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/Ficus-Retusa-236x300.jpg 236w, https:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/Ficus-Retusa.jpg 285w\" sizes=\"(max-width: 236px) 100vw, 236px\" \/><figcaption id=\"caption-attachment-52\" class=\"wp-caption-text\">Foto del Ficus Retusa<\/figcaption><\/figure>\n<p>Esta especie de ficus se cultiva sobre todo como bons\u00e1i, ya que tiene una forma de tronco peculiar. Las hojas son ligeramente alargadas, se asemejan a un \u00f3valo ovalado de color verde, brillante. El pueblo se ramifica bien, de lo que la corona parece amplia. Se va:<\/p>\n<ul>\n<li>Le gusta un lugar luminoso en la habitaci\u00f3n, pero no la luz solar directa.<\/li>\n<li>En verano le gusta el riego frecuente y mantener la tierra h\u00fameda, pero en invierno el riego debe reducirse.<\/li>\n<li>Le gusta la temperatura \u00f3ptima de +59\u00b0F a +77\u00b0F.<\/li>\n<\/ul>\n<h2>Ficus Ginseng Microcarpa<\/h2>\n<figure id=\"attachment_53\" aria-describedby=\"caption-attachment-53\" style=\"width: 236px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" class=\"wp-image-53 size-medium\" src=\"http:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/Ficus-Ginseng-Microcarpa-236x300.jpg\" alt=\"Ficus Ginseng Microcarpa\" width=\"236\" height=\"300\" srcset=\"https:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/Ficus-Ginseng-Microcarpa-236x300.jpg 236w, https:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/Ficus-Ginseng-Microcarpa.jpg 500w\" sizes=\"(max-width: 236px) 100vw, 236px\" \/><figcaption id=\"caption-attachment-53\" class=\"wp-caption-text\">Foto de Ficus Ginseng Microcarpa<\/figcaption><\/figure>\n<p>En su h\u00e1bitat natural, el Ficus Ginseng Microcarpa se comporta de forma bastante agresiva: para continuar su propio crecimiento, ahoga a otra planta. Pero esto no ocurre en el entorno dom\u00e9stico. En la floricultura ornamental, esta especie se cultiva en forma de bons\u00e1i, principalmente por el hecho de que su tronco parece ra\u00edces entrelazadas, que crecen en una trayectoria sinuosa. La copa tiene un aspecto bastante cuidado: son peque\u00f1as \u00abislas\u00bb de ramas cortas con hojas ovaladas de color verde, brillantes. El tronco y las ra\u00edces son de color gris claro. Se va:<\/p>\n<ul>\n<li>Le gusta la penumbra.<\/li>\n<li>No soporta las corrientes de aire.<\/li>\n<li>Temperatura \u00f3ptima de +60,8\u00b0F a +71,6\u00b0F.<\/li>\n<li>El riego es moderado, sin que el suelo se seque.<\/li>\n<\/ul>\n<h2>Ficus Montana<\/h2>\n<figure id=\"attachment_54\" aria-describedby=\"caption-attachment-54\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" class=\"wp-image-54 size-medium\" src=\"http:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/Ficus-Montana-300x300.jpg\" alt=\"Ficus Montana\" width=\"300\" height=\"300\" srcset=\"https:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/Ficus-Montana-300x300.jpg 300w, https:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/Ficus-Montana-150x150.jpg 150w, https:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/Ficus-Montana-230x230.jpg 230w, https:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/Ficus-Montana-365x365.jpg 365w, https:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/Ficus-Montana.jpg 500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-54\" class=\"wp-caption-text\">Foto del Ficus Montana<\/figcaption><\/figure>\n<p>El Ficus Montana es un arbusto rastrero, que en casa se cultiva como planta de ampel. Sus hojas tienen una forma similar a la del roble, de color verde, ligeramente rugosas. En longitud, las hojas alcanzan 8 cm, y en anchura 4 &#8211; 4,5 cm. Los escapos son finos, de color marr\u00f3n-verde. Cuidados:<\/p>\n<ul>\n<li>La temperatura \u00f3ptima para esta planta es de +62,6\u00b0F a +71,6\u00b0F.<\/li>\n<li>Le gusta la luz penumbra o difusa.<\/li>\n<li>Le gusta el riego abundante en primavera y verano, y moderado en oto\u00f1o e invierno.<\/li>\n<\/ul>\n<h2>Ficus Deltoidea<\/h2>\n<figure id=\"attachment_55\" aria-describedby=\"caption-attachment-55\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" class=\"wp-image-55 size-medium\" src=\"http:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/Ficus-Deltoidea-300x300.jpg\" alt=\"Ficus Deltoidea\" width=\"300\" height=\"300\" srcset=\"https:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/Ficus-Deltoidea-300x300.jpg 300w, https:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/Ficus-Deltoidea-150x150.jpg 150w, https:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/Ficus-Deltoidea-230x230.jpg 230w, https:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/Ficus-Deltoidea-365x365.jpg 365w, https:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/Ficus-Deltoidea.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-55\" class=\"wp-caption-text\">Foto del Ficus Deltoidea<\/figcaption><\/figure>\n<p>Este tipo de ficus recibi\u00f3 su nombre por la forma inusual de la hoja. En efecto, las hojas se asemejan a la letra griega \u00abdelta\u00bb, es decir, a un tri\u00e1ngulo, de 4 a 8 cm de largo y 7 cm de ancho, de color verde claro, cori\u00e1ceo y brillante. Hay peque\u00f1os puntos claros en el anverso de las hojas y varios puntos negros en el reverso. La corteza del tronco es gris o gris claro. Los j\u00f3venes ficus deltoides pueden tener siconos esf\u00e9ricos de color amarillo, naranja o rojo. Cuidados:<\/p>\n<ul>\n<li>Temperatura \u00f3ptima: +60,8\u00b0F &#8211; 73,4\u00b0F.<\/li>\n<li>Le gusta la humedad alta, rociar diariamente.<\/li>\n<li>Le gusta la luz, preferentemente la luz difusa.<\/li>\n<\/ul>\n<h2>Ficus Carica<\/h2>\n<figure id=\"attachment_57\" aria-describedby=\"caption-attachment-57\" style=\"width: 264px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" class=\"wp-image-57 size-medium\" src=\"http:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/Ficus-Carica-1-264x300.jpeg\" alt=\"Ficus Carica\" width=\"264\" height=\"300\" srcset=\"https:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/Ficus-Carica-1-264x300.jpeg 264w, https:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/Ficus-Carica-1-rotated.jpeg 400w\" sizes=\"(max-width: 264px) 100vw, 264px\" \/><figcaption id=\"caption-attachment-57\" class=\"wp-caption-text\">Foto de Ficus Carica<\/figcaption><\/figure>\n<p>Es un peque\u00f1o y bonito \u00e1rbol con varias hojas en forma de coraz\u00f3n, bastante grandes. El tronco tiene una corteza gris-marr\u00f3n y brotes d\u00e9bilmente ramificados. Los frutos son higos jugosos, ligeramente aplanados, que pueden ser comestibles o no. Todas las partes de la planta, excepto los frutos, segregan jugo l\u00e1cteo, que puede ser irritante al golpear la piel. Cuidados:<\/p>\n<ul>\n<li>Le gusta la luz, pero es necesario sombrear la planta de la luz solar directa.<\/li>\n<li>Le gustan las temperaturas no muy elevadas en verano &#8211; +60,8\u00b0F &#8211; +68\u00b0F, y en invierno &#8211; +42,8\u00b0F &#8211; +50\u00b0F.<\/li>\n<li>En las estaciones c\u00e1lidas, le gustan las pulverizaciones frecuentes.<\/li>\n<\/ul>\n<h2>Ficus Parcellii<\/h2>\n<figure id=\"attachment_58\" aria-describedby=\"caption-attachment-58\" style=\"width: 225px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" class=\"wp-image-58 size-medium\" src=\"http:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/Ficus-Parcellii-225x300.jpg\" alt=\"Ficus Parcellii\" width=\"225\" height=\"300\" srcset=\"https:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/Ficus-Parcellii-225x300.jpg 225w, https:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/Ficus-Parcellii.jpg 400w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><figcaption id=\"caption-attachment-58\" class=\"wp-caption-text\">Foto del Ficus Parcellii<\/figcaption><\/figure>\n<p>Otro tipo inusual de ficus es el Parcellii. Es un peque\u00f1o \u00e1rbol con hojas alargadas, con puntas afiladas, similares a los aguijones. La planta tiene un color peculiar: hojas verdes con inclusiones o rayas blancas o amarillas. Tienen una longitud de hasta 18 cm. El tronco est\u00e1 ramificado, los brotes est\u00e1n generosamente cubiertos de hojas. Crece con poca rapidez. Se va:<\/p>\n<ul>\n<li>Ficus amante del calor &#8211; +64,4\u00b0F &#8211; +68\u00b0F.<\/li>\n<li>En verano, debe regar con m\u00e1s frecuencia a\u00f1adiendo pulverizaciones.<\/li>\n<li>No tolera un color brillante.<\/li>\n<li>No le gustan las corrientes de aire.<\/li>\n<\/ul>\n<h2>Ficus Hederacea Roxb<\/h2>\n<figure id=\"attachment_59\" aria-describedby=\"caption-attachment-59\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" class=\"wp-image-59 size-medium\" src=\"http:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/Ficus-Hederacea-Roxb-300x225.jpg\" alt=\"Ficus Hederacea Roxb\" width=\"300\" height=\"225\" srcset=\"https:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/Ficus-Hederacea-Roxb-300x225.jpg 300w, https:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/Ficus-Hederacea-Roxb.jpg 500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-59\" class=\"wp-caption-text\">Foto de Ficus Hederacea Roxb<\/figcaption><\/figure>\n<p>Este tipo de ficus se asemeja en todos los sentidos a la hiedra: tanto en la forma de la hoja, como en la capacidad de envolver postes, etc. Las hojas, entre otras cosas, son verdes, cori\u00e1ceas. Los brotes son largos y flexibles. En casa, se cultiva como planta de ampel. Cuidados:<\/p>\n<ul>\n<li>Planta muy exigente con el riego &#8211; el suelo no debe secarse.<\/li>\n<li>Le gusta tener mucho espacio para los brotes.<\/li>\n<\/ul>\n<h2>Ficus Sagittata<\/h2>\n<figure id=\"attachment_60\" aria-describedby=\"caption-attachment-60\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" class=\"wp-image-60 size-medium\" src=\"http:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/Ficus-Sagittata-300x200.jpg\" alt=\"Ficus Sagittata\" width=\"300\" height=\"200\" srcset=\"https:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/Ficus-Sagittata-300x200.jpg 300w, https:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/Ficus-Sagittata.jpg 500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-60\" class=\"wp-caption-text\">Foto de Ficus Sagittata<\/figcaption><\/figure>\n<p>Peque\u00f1o arbusto con brotes rizados. Las hojas son peque\u00f1as, redondeadas, \u00e1speras, con arrugas y un dibujo verde brillante. En la parte inferior del tallo hay unas ventosas, gracias a las cuales la planta puede adherirse a cualquier superficie. Cuidados:<\/p>\n<ul>\n<li>Le gusta la temperatura moderada.<\/li>\n<li>El riego abundante no perjudica a la planta, le encanta la pulverizaci\u00f3n.<\/li>\n<\/ul>\n<h2>Ficus Rubiginosa<\/h2>\n<figure id=\"attachment_61\" aria-describedby=\"caption-attachment-61\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" class=\"wp-image-61 size-medium\" src=\"http:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/Ficus-Rubiginosa-300x297.jpg\" alt=\"Ficus Rubiginosa\" width=\"300\" height=\"297\" srcset=\"https:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/Ficus-Rubiginosa-300x297.jpg 300w, https:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/Ficus-Rubiginosa-150x150.jpg 150w, https:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/Ficus-Rubiginosa.jpg 350w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-61\" class=\"wp-caption-text\">Foto de Ficus Rubiginosa<\/figcaption><\/figure>\n<p>Esta especie de ficus se parece un poco a la goma, pero tiene hojas m\u00e1s cortas. En realidad, las hojas son de color verde oscuro, de forma ovalada, la placa es lisa en la parte superior y \u00e1spera en la parte inferior. Escapan del color marr\u00f3n oxidado. La copa es muy gruesa. La corteza del tronco es lisa, de color gris oscuro, el propio tronco en la base est\u00e1 envuelto con ra\u00edces a\u00e9reas. Cuidados:<\/p>\n<ul>\n<li>La temperatura \u00f3ptima para esta astenia es de +60,8\u00b0F en invierno a +73,4\u00b0F en verano.<\/li>\n<li>Requiere mantener una humedad alta mediante una pulverizaci\u00f3n diaria.<\/li>\n<li>Le gusta el color brillante y difuso.<\/li>\n<\/ul>\n<h2>Ficus Religiosa<\/h2>\n<figure id=\"attachment_62\" aria-describedby=\"caption-attachment-62\" style=\"width: 262px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" class=\"wp-image-62 size-medium\" src=\"http:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/Ficus-Religiosa-262x300.jpg\" alt=\"Ficus Religiosa\" width=\"262\" height=\"300\" srcset=\"https:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/Ficus-Religiosa-262x300.jpg 262w, https:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/Ficus-Religiosa.jpg 411w\" sizes=\"(max-width: 262px) 100vw, 262px\" \/><figcaption id=\"caption-attachment-62\" class=\"wp-caption-text\">Foto de Ficus Religiosa<\/figcaption><\/figure>\n<p>El representante de esta especie en su h\u00e1bitat natural tiene una forma de vida de baniano. Y en casa, a menudo se cultiva como bons\u00e1i. El ficus sagrado tiene un tronco poderoso y brotes grises. Las hojas tienen forma de coraz\u00f3n, de color verde y tacto suave. Cuidados:<\/p>\n<ul>\n<li>No le gusta la luz solar directa, sino que prefiere la luz brillante y dispersa.<\/li>\n<li>No le gustan los cambios bruscos de temperatura, la temperatura m\u00ednima permitida es de +53,6\u00b0F.<\/li>\n<li>Necesita una pulverizaci\u00f3n frecuente en todas las estaciones.<\/li>\n<\/ul>\n<h2>Ficus Cyathistipula<\/h2>\n<figure id=\"attachment_63\" aria-describedby=\"caption-attachment-63\" style=\"width: 227px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" class=\"wp-image-63 size-medium\" src=\"http:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/Ficus-Cyathistipula-227x300.jpg\" alt=\"Ficus Cyathistipula\" width=\"227\" height=\"300\" srcset=\"https:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/Ficus-Cyathistipula-227x300.jpg 227w, https:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/Ficus-Cyathistipula.jpg 280w\" sizes=\"(max-width: 227px) 100vw, 227px\" \/><figcaption id=\"caption-attachment-63\" class=\"wp-caption-text\">Foto de Ficus Cyathistipula<\/figcaption><\/figure>\n<p>Esta especie es muy parecida a sus hermanos: hojas ovaladas alargadas, de hasta 20 cm de largo y hasta 7 cm de ancho, verdes con vetas claras, cori\u00e1ceas. Pero hay una diferencia de peso: esta planta tiene grandes hojas escamosas, de color marr\u00f3n pr\u00edstino. Los frutos de este ficus son bastante comestibles, de color amarillo. Cuidados:<\/p>\n<ul>\n<li>Es una planta muy resistente, soporta bien la sombra.<\/li>\n<li>Tanto la humedad alta como la baja no son perjudiciales para ella.<\/li>\n<\/ul>\n<h2>Ficus Palmeri<\/h2>\n<figure id=\"attachment_64\" aria-describedby=\"caption-attachment-64\" style=\"width: 278px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" class=\"wp-image-64 size-full\" src=\"http:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/Ficus-Palmeri.jpg\" alt=\"Ficus Palmeri\" width=\"278\" height=\"300\" \/><figcaption id=\"caption-attachment-64\" class=\"wp-caption-text\">Foto del Ficus Palmeri<\/figcaption><\/figure>\n<p>El Ficus Palmeri o ficus botella se cultiva como bons\u00e1i en casa, aunque su extra\u00f1a forma no requiere pr\u00e1cticamente ninguna formaci\u00f3n adicional. Las hojas tienen forma de coraz\u00f3n, presentan un patr\u00f3n de venas en relieve en el env\u00e9s de la hoja, y la l\u00e1mina superior tiene un color verde oscuro y un reflejo brillante al sol. Cuidados:<\/p>\n<ul>\n<li>La planta es capaz de acumular humedad en el tronco, por lo que no necesita ser regada con frecuencia.<\/li>\n<li>Es amante del calor.<\/li>\n<\/ul>\n<p>As\u00ed es como muchas de estas incre\u00edbles plantas podemos tener el placer de tenerlas en casa. Ficus trenzado y al fin y al cabo, no son todas las manifestaciones de ficus que existen en la naturaleza, as\u00ed como en la floricultura ornamental.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La mayor\u00eda de la gente piensa que s\u00f3lo existe un tipo de Ficus, pero en realidad, este \u00e1rbol en particular viene en una variedad de formas y tama\u00f1os basados en la variedad espec\u00edfica. Por ejemplo, algunas de las opciones m\u00e1s<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/ficusplant.org\/es\/wp-json\/wp\/v2\/pages\/5257"}],"collection":[{"href":"https:\/\/ficusplant.org\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ficusplant.org\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ficusplant.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ficusplant.org\/es\/wp-json\/wp\/v2\/comments?post=5257"}],"version-history":[{"count":2,"href":"https:\/\/ficusplant.org\/es\/wp-json\/wp\/v2\/pages\/5257\/revisions"}],"predecessor-version":[{"id":5259,"href":"https:\/\/ficusplant.org\/es\/wp-json\/wp\/v2\/pages\/5257\/revisions\/5259"}],"wp:attachment":[{"href":"https:\/\/ficusplant.org\/es\/wp-json\/wp\/v2\/media?parent=5257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}