{"id":5352,"date":"2020-11-08T14:21:34","date_gmt":"2020-11-08T14:21:34","guid":{"rendered":"https:\/\/ficusplant.org\/?page_id=5352"},"modified":"2022-05-12T07:21:55","modified_gmt":"2022-05-12T07:21:55","slug":"ficus-palmeri","status":"publish","type":"page","link":"https:\/\/ficusplant.org\/fr\/ficus-palmeri\/","title":{"rendered":"Ficus Palmeri : Soins, multiplication et transplantation"},"content":{"rendered":"<p>Ficus Palmeri est un indig\u00e8ne du Mexique et de la Californie. Parmi les autres repr\u00e9sentants du genre Ficus Palmeri se distingue par la forme originale du tronc, qui ressemble \u00e0 une bouteille &#8211; \u00e0 la base de la tige est plus large, et au sommet de la tige pense et se termine dans un faisceau de couronnes. Un tel \u00ab\u00a0design\u00a0\u00bb inhabituel est n\u00e9cessaire pour que la plante accumule l&rsquo;humidit\u00e9 et soit capable de r\u00e9sister \u00e0 une s\u00e9cheresse prolong\u00e9e.<\/p>\n<p><iframe loading=\"lazy\" title=\"Ficus palmeri\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/5FCgK_AHpUc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p>Dans les conditions naturelles, souvent au d\u00e9but de la vie se comporte comme un \u00e9piphyte, tressant avec ses racines la plante sur laquelle il s&rsquo;est install\u00e9. G\u00e9n\u00e9ralement, il s&rsquo;agit de cactus ou d&rsquo;autres arbustes. Dans les terrains rocheux secs ne d\u00e9passe pas la marque de 4 m de longueur. Dans les zones \u00e0 plus forte humidit\u00e9 peut s&rsquo;\u00e9tendre jusqu&rsquo;\u00e0 9 m.<\/p>\n<p>Les feuilles du Ficus Palmeri ont une forme de c\u0153ur, atteignant 15 cm de longueur et 12 cm de largeur. La plaque foliaire est vert clair, coriace, brillante avec une nervure prononc\u00e9e qui forme un motif en relief sur la face arri\u00e8re. L&rsquo;\u00e9corce de la plante a une teinte blanc cr\u00e8me, atteignant parfois le jaune.<\/p>\n<figure id=\"attachment_198\" aria-describedby=\"caption-attachment-198\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" class=\"wp-image-198 size-medium\" src=\"http:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/IMG_6836-300x240.jpg\" alt=\"Ficus Palmeri \" width=\"300\" height=\"240\" srcset=\"https:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/IMG_6836-300x240.jpg 300w, https:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/IMG_6836.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-198\" class=\"wp-caption-text\">Ficus Palmeri photo<\/figcaption><\/figure>\n<p>Le Ficus Palmeri en culture domestique a une valeur tr\u00e8s d\u00e9corative, car il peut \u00eatre cultiv\u00e9 dans le style bonsa\u00ef. Il n&rsquo;a m\u00eame pas besoin d&rsquo;une taille suppl\u00e9mentaire, puisque la forme de la plante est d\u00e9j\u00e0 assez \u00e9trange. Il faut toutefois noter que le Ficus Palmer ne peut \u00eatre cultiv\u00e9 en tant que tel qu&rsquo;\u00e0 partir de graines ; en cas de reproduction v\u00e9g\u00e9tative, il deviendra un arbre ordinaire.<\/p>\n<h2>Prendre soin du Ficus Palmeri \u00e0 la maison<\/h2>\n<p>Prendre soin de soi Ficus Palmeri sp\u00e9cial ne n\u00e9cessite pas. Ainsi, cette plante devient non seulement un achat d\u00e9coratif exquis, mais aussi un animal de compagnie vert peu exigeant.<\/p>\n<p><img loading=\"lazy\" class=\"size-medium wp-image-328 aligncenter\" src=\"http:\/\/ficusplant.org\/wp-content\/uploads\/2021\/06\/Screenshot_6-1-281x300.png\" alt=\"Ficus Palmeri at home\" width=\"400\" height=\"350\" \/><\/p>\n<ul>\n<li><strong>L&rsquo;\u00e9clairage :<\/strong> Le Ficus Palmeri est une plante qui aime la lumi\u00e8re, elle appr\u00e9cie donc une lumi\u00e8re vive et diffuse. Il est pr\u00e9f\u00e9rable d&rsquo;ombrager la plante de la lumi\u00e8re directe du soleil. L&rsquo;endroit le plus confortable pour le ficus est sur les fen\u00eatres est ou ouest. Le sud et le nord conviennent \u00e9galement, mais dans le cas du sud, vous devez prendre des pr\u00e9cautions pour \u00e9viter les rayons du soleil de midi sur le Ficus Palmeri.<\/li>\n<li><strong>Temp\u00e9rature :<\/strong> la temp\u00e9rature optimale en \u00e9t\u00e9 est de + 73,4\u00b0F \u00e0 + 77\u00b0F. En hiver, la meilleure option sera &#8211; de +53.6\u00b0F \u00e0 +59\u00b0F.<\/li>\n<li><strong>Arrosage :<\/strong> en \u00e9t\u00e9, l&rsquo;irrigation doit \u00eatre assez abondante, mais en hiver, elle doit \u00eatre r\u00e9duite. Pendant cette p\u00e9riode, la plante est au repos et perd ses feuilles. Au printemps, l&rsquo;arrosage reprend.<\/li>\n<li><strong>Humidit\u00e9 de l&rsquo;air :<\/strong> en toute saison, il est n\u00e9cessaire d&rsquo;effectuer de fr\u00e9quentes pulv\u00e9risations d&rsquo;eau propre \u00e0 temp\u00e9rature ambiante.<\/li>\n<li><strong>Transplantation :<\/strong> Comme les autres repr\u00e9sentants des ficus, les jeunes Ficus Palmeri ont besoin d&rsquo;une transplantation annuelle, qui se fait au printemps. Pendant cette proc\u00e9dure, la plante a besoin d&rsquo;augmenter le pot, mais pas la profondeur, mais la largeur, car le syst\u00e8me racinaire se d\u00e9veloppe pr\u00e8s de la surface. Les ficus plus matures sont transplant\u00e9s une fois tous les 1 \u00e0 2 ans. Et certaines personnes n&rsquo;ont besoin de changer que la couche sup\u00e9rieure du sol.<\/li>\n<li><strong>Fertilisation :<\/strong> du printemps \u00e0 la fin de l&rsquo;\u00e9t\u00e9, on applique des engrais min\u00e9raux et organiques.<\/li>\n<li><strong>Reproduction :<\/strong> Le Ficus Palmeri se multiplie par bouturage et par l&rsquo;utilisation de graines.<\/li>\n<\/ul>\n<h2>Maladies et ravageurs<\/h2>\n<p>Le Ficus Palmeri peut \u00eatre affect\u00e9 par des parasites tels que le ver farineux, le bouclier et le t\u00e9tranyque.<\/p>\n<ul>\n<li><strong>Le ver poudreux :<\/strong> il se pr\u00e9sente sous la forme d&rsquo;amas blancs et pelucheux. Vous pouvez vous en d\u00e9barrasser en retirant un coton-tige imbib\u00e9 d&rsquo;eau savonneuse et en pulv\u00e9risant de l&rsquo;infusion de tabac, de l&rsquo;infusion d&rsquo;ail et du bouillon cyclamenoid.<\/li>\n<li><strong>Bouclier :<\/strong> Ressemble \u00e0 des taches de croissance jaunes qui font jaunir et vriller une feuille enti\u00e8re. Pour s&rsquo;en d\u00e9barrasser, il faut d&rsquo;abord gratter l&rsquo;insecte sur les feuilles d&rsquo;une plante infect\u00e9e, puis laver le ficus entier \u00e0 l&rsquo;eau chaude ou \u00e0 l&rsquo;eau savonneuse. Vous pouvez \u00e9galement utiliser des agents chimiques sp\u00e9ciaux.<\/li>\n<li><strong>T\u00e9tranyque :<\/strong> une toile d&rsquo;araign\u00e9e et de petites araign\u00e9es rouges apparaissent. Il est n\u00e9cessaire d&rsquo;essuyer les feuilles avec de l&rsquo;eau savonneuse, et en cas de d\u00e9g\u00e2ts importants &#8211; de pulv\u00e9riser des insecticides.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Ficus Palmeri est un indig\u00e8ne du Mexique et de la Californie. Parmi les autres repr\u00e9sentants du genre Ficus Palmeri se distingue par la forme originale du tronc, qui ressemble \u00e0 une bouteille &#8211; \u00e0 la base de la tige est<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/ficusplant.org\/fr\/wp-json\/wp\/v2\/pages\/5352"}],"collection":[{"href":"https:\/\/ficusplant.org\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ficusplant.org\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ficusplant.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ficusplant.org\/fr\/wp-json\/wp\/v2\/comments?post=5352"}],"version-history":[{"count":2,"href":"https:\/\/ficusplant.org\/fr\/wp-json\/wp\/v2\/pages\/5352\/revisions"}],"predecessor-version":[{"id":5354,"href":"https:\/\/ficusplant.org\/fr\/wp-json\/wp\/v2\/pages\/5352\/revisions\/5354"}],"wp:attachment":[{"href":"https:\/\/ficusplant.org\/fr\/wp-json\/wp\/v2\/media?parent=5352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}