{"id":6679,"date":"2020-12-07T15:19:44","date_gmt":"2020-12-07T15:19:44","guid":{"rendered":"https:\/\/ficusplant.org\/?page_id=6679"},"modified":"2022-06-16T07:01:18","modified_gmt":"2022-06-16T07:01:18","slug":"ficus-benghalensis","status":"publish","type":"page","link":"https:\/\/ficusplant.org\/fr\/ficus-benghalensis\/","title":{"rendered":"Figuier des banians : Conseils pour la reproduction et le soin des transplantations"},"content":{"rendered":"<p>Le Figuier des banians, plus connu dans le monde du jardinage sous le nom de \u00ab\u00a0figue \u00e9trangleuse\u00a0\u00bb, \u00ab\u00a0figue du Bengale\u00a0\u00bb et \u00ab\u00a0arbre banian\u00a0\u00bb, est un choix tr\u00e8s populaire pour une plante d&rsquo;int\u00e9rieur d\u00e9corative et fonctionnelle. Ce type de figue a la r\u00e9putation d&rsquo;\u00eatre particuli\u00e8rement polyvalent dans l&rsquo;art du bonsa\u00ef. Bien que la friandise elle-m\u00eame pr\u00e9sente de nombreuses caract\u00e9ristiques physiques agr\u00e9ables, elle est \u00e9galement consid\u00e9r\u00e9e comme un arbre sacr\u00e9 par les peuples bouddhistes et hindous, et on la trouve g\u00e9n\u00e9ralement florissante \u00e0 l&rsquo;ext\u00e9rieur des temples religieux. Si vous cherchez une plante d&rsquo;int\u00e9rieur qui a beaucoup de caract\u00e8re, c&rsquo;est une plante qui m\u00e9rite d&rsquo;\u00eatre consid\u00e9r\u00e9e !<\/p>\n<h2>Habitat<\/h2>\n<p>Le Figuier des banians est originaire d&rsquo;Inde, du Pakistan et du Sri Lanka. Dans son habitat d&rsquo;origine, cette vari\u00e9t\u00e9 de figuier est plus susceptible d&rsquo;\u00eatre trouv\u00e9e dans les r\u00e9gions de for\u00eat tropicale de ces r\u00e9gions o\u00f9 elle peut profiter de la mousson occasionnelle. Ces arbres sont tr\u00e8s appr\u00e9ci\u00e9s en Inde, \u00e0 tel point que l&rsquo;on voit souvent ce type de ficus pousser autour des temples, des parcs publics et des jardins publics. Comme la plupart des autres esp\u00e8ces de figuiers, le Figuier des banians est un tr\u00e8s grand arbre \u00e0 l&rsquo;\u00e9tat sauvage et a besoin de beaucoup d&rsquo;espace pour pousser. On le trouve couramment dans les for\u00eats tropicales car l&rsquo;environnement humide et spacieux est l&rsquo;endroit id\u00e9al pour que le ficus se d\u00e9veloppe.<\/p>\n<p><iframe loading=\"lazy\" title=\"How To Care For: Banyan Fig\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/YK7DZpzP8qU?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p>Dans son habitat naturel, le Figuier des banians peut \u00eatre un arbre de 20, rarement jusqu&rsquo;\u00e0 30 m\u00e8tres de haut. Dans le salon, le banian \u00e0 croissance verticale fait \u00e9galement partie des grandes plantes d&rsquo;int\u00e9rieur, mais dans le conteneur, il ne d\u00e9passe pas le plafond. D\u00e8s que les extr\u00e9mit\u00e9s des pousses atteignent la zone plus sombre au-dessus de l&rsquo;ouverture de la fen\u00eatre, elles cessent de cro\u00eetre.<\/p>\n<p>Les feuilles de la plante correspondent \u00e0 son \u00e9chelle &#8211; parfois jusqu&rsquo;\u00e0 25 cm. Il s&rsquo;agit d&rsquo;une plaque de cuir vert avec un petit poil et une veine claire au milieu. A la maison, le Figuier des banians un arbre qui, comme son cong\u00e9n\u00e8re \u00ab\u00a0sauvage\u00a0\u00bb, se d\u00e9chire rapidement. Bien s\u00fbr, il ne laisse pas de racines a\u00e9riennes dans le pot, mais cette plante a tout de m\u00eame besoin de beaucoup d&rsquo;espace. Ce type de ficus est donc plus adapt\u00e9 aux bureaux, aux jardins d&rsquo;hiver, aux serres ou aux grands salons. Mais les propri\u00e9taires d&rsquo;un petit espace de vie ne doivent pas s&rsquo;inqui\u00e9ter, car le Benghalensis Le repr\u00e9sentant des arbres \u00e0 feuilles persistantes est parfait pour la culture sous forme de bonsa\u00ef.<\/p>\n<div id='gallery-1' class='gallery galleryid-6679 gallery-columns-2 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<img width=\"289\" height=\"300\" src=\"https:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/fikus-bengalskiy-bonsai-photo-289x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" aria-describedby=\"gallery-1-1303\" srcset=\"https:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/fikus-bengalskiy-bonsai-photo-289x300.jpg 289w, https:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/fikus-bengalskiy-bonsai-photo.jpg 298w\" sizes=\"(max-width: 289px) 100vw, 289px\" \/>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-1303'>\n\t\t\t\tFiguier des banians Bonsai photo\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<img width=\"225\" height=\"300\" src=\"https:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/fikus-bengalskiy-photo-225x300.jpg\" class=\"attachment-medium size-medium\" alt=\"Banyan-Feige\" loading=\"lazy\" aria-describedby=\"gallery-1-1319\" srcset=\"https:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/fikus-bengalskiy-photo-225x300.jpg 225w, https:\/\/ficusplant.org\/wp-content\/uploads\/2020\/12\/fikus-bengalskiy-photo.jpg 450w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-1319'>\n\t\t\t\tFiguier des banians photo\n\t\t\t\t<\/figcaption><\/figure>\n\t\t<\/div>\n\n<h2>Prendre soin du Figuier des banians \u00e0 la maison<\/h2>\n<p>Le Figuier des banians n&rsquo;exige pas que les soins qu&rsquo;on lui prodigue soient g\u00eanants. Mais l&rsquo;inattention, le manque de soin et l&rsquo;indiff\u00e9rence peuvent r\u00e9agir en faisant tomber les feuilles. Il suffit, entre autres, de suivre quelques r\u00e8gles simples pour que le ficus se sente \u00e0 l&rsquo;aise et soit remerci\u00e9 par une croissance luxuriante et une verdure saine.<\/p>\n<p><img loading=\"lazy\" class=\"size-medium wp-image-298 aligncenter\" src=\"http:\/\/ficusplant.org\/wp-content\/uploads\/2021\/06\/Screenshot_6-300x284.png\" alt=\"Ficus Audrey\" width=\"400\" height=\"384\" \/><\/p>\n<ul>\n<li><strong>\u00c9clairage :<\/strong> Lorsque vous choisissez l&#8217;emplacement id\u00e9al pour ce type de ficus, essayez d&rsquo;\u00e9viter de le placer pr\u00e8s d&rsquo;une fen\u00eatre o\u00f9 il pourrait \u00eatre expos\u00e9 \u00e0 la lumi\u00e8re directe du soleil. Rappelez-vous que cet arbre aime la for\u00eat tropicale o\u00f9 il serait partiellement ombrag\u00e9 par d&rsquo;autres arbres. Par cons\u00e9quent, l&rsquo;endroit id\u00e9al \u00e0 l&rsquo;int\u00e9rieur serait un endroit qui re\u00e7oit soit une ombre partielle, soit une lumi\u00e8re vive et filtr\u00e9e.<\/li>\n<li><strong>La temp\u00e9rature :<\/strong> La temp\u00e9rature id\u00e9ale pour une plante d&rsquo;int\u00e9rieur ficus se situe entre 70 et 80 degr\u00e9s Fahrenheit, ce qui est consid\u00e9r\u00e9 comme une fourchette assez moyenne pour la plupart des maisons aux \u00c9tats-Unis. Si n\u00e9cessaire, cet arbre peut supporter des temp\u00e9ratures allant jusqu&rsquo;\u00e0 environ 55 degr\u00e9s Fahrenheit, mais il ne doit pas \u00eatre expos\u00e9 \u00e0 des temp\u00e9ratures aussi basses de fa\u00e7on r\u00e9guli\u00e8re, sinon ses feuilles commenceront \u00e0 jaunir et \u00e0 tomber rapidement.<\/li>\n<li><strong>Arrosage :<\/strong> La plante aime les arrosages r\u00e9guliers et abondants en toutes saisons, car ce ficus n&rsquo;a pas de p\u00e9riode d&rsquo;affaiblissement de sa croissance. Cependant, avant le prochain arrosage, il faut attendre que la couche sup\u00e9rieure du sol soit s\u00e8che.<\/li>\n<li><strong>Humidit\u00e9 de l&rsquo;air :<\/strong> ce type pr\u00e9f\u00e8re une humidit\u00e9 de l&rsquo;air plus \u00e9lev\u00e9e, mais en raison de la taille de la pulv\u00e9risation seule ne suffit pas. Il est recommand\u00e9 d&rsquo;essuyer les feuilles avec une \u00e9ponge douce ou un chiffon.<br \/>\nEn hiver, pendant la saison de chauffage, le Figuier des banians a int\u00e9r\u00eat \u00e0 s&rsquo;\u00e9loigner des radiateurs, tout en assurant un \u00e9clairage pr\u00e9alable.<\/li>\n<li><strong>Rempotage :<\/strong> Le banyan a besoin d&rsquo;\u00eatre rempot\u00e9 moins fr\u00e9quemment que les autres plantes d&rsquo;int\u00e9rieur. Ce n&rsquo;est que lorsque le pot est compl\u00e8tement enracin\u00e9 que vous mettez la plante dans un r\u00e9cipient un peu plus grand. F\u00e9vrier \u00e0 mars est la meilleure p\u00e9riode pour cela.<\/li>\n<li><strong>Alimentation :<\/strong> il faut \u00eatre tr\u00e8s prudent, car vous ne pouvez nourrir le Figuier des banians que 1 \u00e0 2 fois par mois, en divisant la dose d&rsquo;engrais recommand\u00e9e sur l&#8217;emballage. Il est pr\u00e9f\u00e9rable d&rsquo;utiliser des granul\u00e9s, universels.<\/li>\n<li><strong>Coupe :<\/strong> Normalement, vous n&rsquo;avez pas besoin de couper l&rsquo;imposant feuillage de la plante ornementale.<\/li>\n<li><strong>Reproduction :<\/strong> Le Figuier des banians se multiplie par le tirage, les robinets \u00e0 air et les graines. Si vous n&rsquo;\u00eates pas un professionnel de la reproduction des ficus, il est pr\u00e9f\u00e9rable d&rsquo;utiliser de jeunes boutures avec plusieurs feuilles. L&rsquo;enracinement se fait de pr\u00e9f\u00e9rence dans un m\u00e9lange de tourbe et de sable. De cette fa\u00e7on, les racines se d\u00e9velopperont plus rapidement que dans l&rsquo;eau. La m\u00e9thode la plus fiable de propagation des h\u00e9v\u00e9as est consid\u00e9r\u00e9e comme le moussage. La proc\u00e9dure est un peu lourde et longue, mais prometteuse si le banian a perdu ses feuilles et que vous voulez le renouveler. On fait une incision sur le tronc juste en dessous du n\u0153ud foliaire le plus bas. La coupe doit \u00eatre oblique de bas en haut et sa longueur doit \u00eatre \u00e9gale \u00e0 la moiti\u00e9 du diam\u00e8tre.<\/li>\n<li><strong>Attention :<\/strong> Ne pas couper trop profond\u00e9ment. Bourrez l&rsquo;incision de mousse, mais avec pr\u00e9caution. Si vous bourrez trop fort, le tronc se cassera en deux. Enroulez ensuite un paquet de mousse humide autour de l&rsquo;incision comme un pansement. Par-dessus vient une feuille de plastique transparent, que vous attachez au-dessus et au-dessous de l&rsquo;incision sur le tronc. Les racines vont se former sous la feuille de plastique. D\u00e8s qu&rsquo;elles poussent \u00e0 travers la mousse, vous enlevez le film plastique, coupez le tronc sous les racines et ins\u00e9rez les boutures de t\u00eate enracin\u00e9es avec de la mousse.<\/li>\n<li><strong>Autres soins :<\/strong> Les grandes feuilles de ces plantes appr\u00e9cient une humidit\u00e9 \u00e9lev\u00e9e. Vaporisez de temps en temps le feuillage &#8211; surtout pendant la saison de chauffage hivernal avec un air sec &#8211; avec de l&rsquo;eau douce et sans calcaire. Si n\u00e9cessaire, nettoyez les feuilles du ficus de la poussi\u00e8re avec un chiffon doux.<\/li>\n<\/ul>\n<p>Comme vous pouvez le constater, le Figuier des banians est l&rsquo;une des plantes les plus sans pr\u00e9tention, vous n&rsquo;aurez donc aucun mal \u00e0 en prendre soin.<\/p>\n<h2>Maladies et ravageurs<\/h2>\n<p>En g\u00e9n\u00e9ral, cette esp\u00e8ce de ficus n&rsquo;est pas tr\u00e8s sensible aux \u00ab\u00a0attaques\u00a0\u00bb de ravageurs, mais si cela se produit, il peut souvent s&rsquo;agir d&rsquo;une t\u00e9tranyque, d&rsquo;un bouclier et de thrips. Dans ce cas, la plante peut \u00eatre lav\u00e9e sous une douche chaude ou essuy\u00e9e avec une \u00e9ponge humide, et trait\u00e9e avec des produits chimiques sp\u00e9ciaux, notamment une solution savonneuse. Les maladies sont beaucoup plus fr\u00e9quentes, mais elles proviennent toutes d&rsquo;un mauvais entretien. Afin d&rsquo;aider votre ficus, vous devez rep\u00e9rer les erreurs de soins :<\/p>\n<ul>\n<li>Si la temp\u00e9rature de l&rsquo;air est inf\u00e9rieure aux limites mentionn\u00e9es pr\u00e9c\u00e9demment, le ficus peut commencer \u00e0 fl\u00e9trir ses feuilles.<\/li>\n<li>La plante manque de lumi\u00e8re &#8211; les feuilles peuvent devenir plus petites.<\/li>\n<li>Versez dans le ficus &#8211; des taches jaunes apparaissent sur les feuilles.<\/li>\n<li>S&rsquo;il y a un manque d&rsquo;engrais, l&rsquo;ossification ralentit et les feuilles perdent leur couleur.<\/li>\n<li>La fi\u00e8vre et l&rsquo;air sec peuvent provoquer des taches brunes sur les bords.<\/li>\n<\/ul>\n<p>Nous avons donc fait connaissance avec un autre repr\u00e9sentant de la flore &#8211; Figuier des banians et nous nous sommes assur\u00e9s que m\u00eame une plante aussi inhabituelle peut facilement pousser \u00e0 la maison.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Figuier des banians, plus connu dans le monde du jardinage sous le nom de \u00ab\u00a0figue \u00e9trangleuse\u00a0\u00bb, \u00ab\u00a0figue du Bengale\u00a0\u00bb et \u00ab\u00a0arbre banian\u00a0\u00bb, est un choix tr\u00e8s populaire pour une plante d&rsquo;int\u00e9rieur d\u00e9corative et fonctionnelle. Ce type de figue a<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/ficusplant.org\/fr\/wp-json\/wp\/v2\/pages\/6679"}],"collection":[{"href":"https:\/\/ficusplant.org\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ficusplant.org\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ficusplant.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ficusplant.org\/fr\/wp-json\/wp\/v2\/comments?post=6679"}],"version-history":[{"count":3,"href":"https:\/\/ficusplant.org\/fr\/wp-json\/wp\/v2\/pages\/6679\/revisions"}],"predecessor-version":[{"id":12123,"href":"https:\/\/ficusplant.org\/fr\/wp-json\/wp\/v2\/pages\/6679\/revisions\/12123"}],"wp:attachment":[{"href":"https:\/\/ficusplant.org\/fr\/wp-json\/wp\/v2\/media?parent=6679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}